{"id":30799,"date":"2022-08-26T15:14:02","date_gmt":"2022-08-26T15:14:02","guid":{"rendered":"https:\/\/westoba.com\/wp-content\/uploads\/2022\/08\/Collabria_BacktoSchoolOffer_HomepageBanner_1920x550.jpg"},"modified":"2022-08-26T15:14:02","modified_gmt":"2022-08-26T15:14:02","slug":"collabria_backtoschooloffer_homepagebanner_1920x550-2","status":"inherit","type":"attachment","link":"https:\/\/westoba.com\/pa\/collabria_backtoschooloffer_homepagebanner_1920x550-2\/","title":{"rendered":"Collabria_BacktoSchoolOffer_HomepageBanner_1920x550"},"author":29,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_links_to":"","_links_to_target":""},"class_list":["post-30799","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Collabria_BacktoSchoolOffer_HomepageBanner_1920x550 - Westoba<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/westoba.com\/wp-content\/uploads\/2022\/08\/Collabria_BacktoSchoolOffer_HomepageBanner_1920x550.jpg\" \/>\n<meta property=\"og:locale\" content=\"pa_IN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Collabria_BacktoSchoolOffer_HomepageBanner_1920x550 - Westoba\" \/>\n<meta property=\"og:url\" content=\"https:\/\/westoba.com\/wp-content\/uploads\/2022\/08\/Collabria_BacktoSchoolOffer_HomepageBanner_1920x550.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Westoba\" \/>\n<meta property=\"og:image\" content=\"https:\/\/westoba.com\/wp-content\/uploads\/2022\/08\/Collabria_BacktoSchoolOffer_HomepageBanner_1920x550.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"550\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/westoba.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Collabria_BacktoSchoolOffer_HomepageBanner_1920x550.jpg\",\"url\":\"https:\\\/\\\/westoba.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Collabria_BacktoSchoolOffer_HomepageBanner_1920x550.jpg\",\"name\":\"Collabria_BacktoSchoolOffer_HomepageBanner_1920x550 - Westoba\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/westoba.com\\\/#website\"},\"datePublished\":\"2022-08-26T15:14:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/westoba.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Collabria_BacktoSchoolOffer_HomepageBanner_1920x550.jpg#breadcrumb\"},\"inLanguage\":\"pa-IN\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/westoba.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Collabria_BacktoSchoolOffer_HomepageBanner_1920x550.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/westoba.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Collabria_BacktoSchoolOffer_HomepageBanner_1920x550.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/westoba.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Collabria_BacktoSchoolOffer_HomepageBanner_1920x550\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/westoba.com\\\/#website\",\"url\":\"https:\\\/\\\/westoba.com\\\/\",\"name\":\"Westoba\",\"description\":\"Credit Union\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/westoba.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pa-IN\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Collabria_BacktoSchoolOffer_HomepageBanner_1920x550 - Westoba","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/westoba.com\/wp-content\/uploads\/2022\/08\/Collabria_BacktoSchoolOffer_HomepageBanner_1920x550.jpg","og_locale":"pa_IN","og_type":"article","og_title":"Collabria_BacktoSchoolOffer_HomepageBanner_1920x550 - Westoba","og_url":"https:\/\/westoba.com\/wp-content\/uploads\/2022\/08\/Collabria_BacktoSchoolOffer_HomepageBanner_1920x550.jpg","og_site_name":"Westoba","og_image":[{"width":1920,"height":550,"url":"https:\/\/westoba.com\/wp-content\/uploads\/2022\/08\/Collabria_BacktoSchoolOffer_HomepageBanner_1920x550.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/westoba.com\/wp-content\/uploads\/2022\/08\/Collabria_BacktoSchoolOffer_HomepageBanner_1920x550.jpg","url":"https:\/\/westoba.com\/wp-content\/uploads\/2022\/08\/Collabria_BacktoSchoolOffer_HomepageBanner_1920x550.jpg","name":"Collabria_BacktoSchoolOffer_HomepageBanner_1920x550 - Westoba","isPartOf":{"@id":"https:\/\/westoba.com\/#website"},"datePublished":"2022-08-26T15:14:02+00:00","breadcrumb":{"@id":"https:\/\/westoba.com\/wp-content\/uploads\/2022\/08\/Collabria_BacktoSchoolOffer_HomepageBanner_1920x550.jpg#breadcrumb"},"inLanguage":"pa-IN","potentialAction":[{"@type":"ReadAction","target":["https:\/\/westoba.com\/wp-content\/uploads\/2022\/08\/Collabria_BacktoSchoolOffer_HomepageBanner_1920x550.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/westoba.com\/wp-content\/uploads\/2022\/08\/Collabria_BacktoSchoolOffer_HomepageBanner_1920x550.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/westoba.com\/"},{"@type":"ListItem","position":2,"name":"Collabria_BacktoSchoolOffer_HomepageBanner_1920x550"}]},{"@type":"WebSite","@id":"https:\/\/westoba.com\/#website","url":"https:\/\/westoba.com\/","name":"Westoba","description":"Credit Union","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/westoba.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pa-IN"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/westoba.com\/wp-content\/uploads\/2022\/08\/Collabria_BacktoSchoolOffer_HomepageBanner_1920x550.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"86\" src=\"https:\/\/westoba.com\/wp-content\/uploads\/2022\/08\/Collabria_BacktoSchoolOffer_HomepageBanner_1920x550-300x86.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/westoba.com\/wp-content\/uploads\/2022\/08\/Collabria_BacktoSchoolOffer_HomepageBanner_1920x550-300x86.jpg 300w, https:\/\/westoba.com\/wp-content\/uploads\/2022\/08\/Collabria_BacktoSchoolOffer_HomepageBanner_1920x550-1024x293.jpg 1024w, https:\/\/westoba.com\/wp-content\/uploads\/2022\/08\/Collabria_BacktoSchoolOffer_HomepageBanner_1920x550-768x220.jpg 768w, https:\/\/westoba.com\/wp-content\/uploads\/2022\/08\/Collabria_BacktoSchoolOffer_HomepageBanner_1920x550-1536x440.jpg 1536w, https:\/\/westoba.com\/wp-content\/uploads\/2022\/08\/Collabria_BacktoSchoolOffer_HomepageBanner_1920x550-700x201.jpg 700w, https:\/\/westoba.com\/wp-content\/uploads\/2022\/08\/Collabria_BacktoSchoolOffer_HomepageBanner_1920x550.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1920,"height":550,"file":"2022\/08\/Collabria_BacktoSchoolOffer_HomepageBanner_1920x550.jpg","filesize":698609,"sizes":{"medium":{"file":"Collabria_BacktoSchoolOffer_HomepageBanner_1920x550-300x86.jpg","width":300,"height":86,"filesize":10282,"mime_type":"image\/jpeg","source_url":"https:\/\/westoba.com\/wp-content\/uploads\/2022\/08\/Collabria_BacktoSchoolOffer_HomepageBanner_1920x550-300x86.jpg"},"large":{"file":"Collabria_BacktoSchoolOffer_HomepageBanner_1920x550-1024x293.jpg","width":1024,"height":293,"filesize":61984,"mime_type":"image\/jpeg","source_url":"https:\/\/westoba.com\/wp-content\/uploads\/2022\/08\/Collabria_BacktoSchoolOffer_HomepageBanner_1920x550-1024x293.jpg"},"thumbnail":{"file":"Collabria_BacktoSchoolOffer_HomepageBanner_1920x550-172x120.jpg","width":172,"height":120,"filesize":7642,"mime_type":"image\/jpeg","source_url":"https:\/\/westoba.com\/wp-content\/uploads\/2022\/08\/Collabria_BacktoSchoolOffer_HomepageBanner_1920x550-172x120.jpg"},"medium_large":{"file":"Collabria_BacktoSchoolOffer_HomepageBanner_1920x550-768x220.jpg","width":768,"height":220,"filesize":41709,"mime_type":"image\/jpeg","source_url":"https:\/\/westoba.com\/wp-content\/uploads\/2022\/08\/Collabria_BacktoSchoolOffer_HomepageBanner_1920x550-768x220.jpg"},"1536x1536":{"file":"Collabria_BacktoSchoolOffer_HomepageBanner_1920x550-1536x440.jpg","width":1536,"height":440,"filesize":111695,"mime_type":"image\/jpeg","source_url":"https:\/\/westoba.com\/wp-content\/uploads\/2022\/08\/Collabria_BacktoSchoolOffer_HomepageBanner_1920x550-1536x440.jpg"},"wcu_feature":{"file":"Collabria_BacktoSchoolOffer_HomepageBanner_1920x550-700x201.jpg","width":700,"height":201,"filesize":36698,"mime_type":"image\/jpeg","source_url":"https:\/\/westoba.com\/wp-content\/uploads\/2022\/08\/Collabria_BacktoSchoolOffer_HomepageBanner_1920x550-700x201.jpg"},"wcu_team_feed":{"file":"Collabria_BacktoSchoolOffer_HomepageBanner_1920x550-960x550.jpg","width":960,"height":550,"filesize":100357,"mime_type":"image\/jpeg","source_url":"https:\/\/westoba.com\/wp-content\/uploads\/2022\/08\/Collabria_BacktoSchoolOffer_HomepageBanner_1920x550-960x550.jpg"},"full":{"file":"Collabria_BacktoSchoolOffer_HomepageBanner_1920x550.jpg","width":1920,"height":550,"mime_type":"image\/jpeg","source_url":"https:\/\/westoba.com\/wp-content\/uploads\/2022\/08\/Collabria_BacktoSchoolOffer_HomepageBanner_1920x550.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/westoba.com\/wp-content\/uploads\/2022\/08\/Collabria_BacktoSchoolOffer_HomepageBanner_1920x550.jpg","filename":"Collabria_BacktoSchoolOffer_HomepageBanner_1920x550.jpg","filesize":698609,"_links":{"self":[{"href":"https:\/\/westoba.com\/pa\/wp-json\/wp\/v2\/media\/30799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/westoba.com\/pa\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/westoba.com\/pa\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/westoba.com\/pa\/wp-json\/wp\/v2\/users\/29"}]}}